{"id":33219,"date":"2017-11-03T07:37:08","date_gmt":"2017-11-03T07:37:08","guid":{"rendered":"https:\/\/chennaivision.com\/tamil-movies\/?p=33219"},"modified":"2017-11-03T07:37:08","modified_gmt":"2017-11-03T07:37:08","slug":"dhruva-natchathiram-working-images","status":"publish","type":"post","link":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/","title":{"rendered":"DHRUVA NATCHATHIRAM WORKING IMAGES"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-33219 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram2\/'><img width=\"64\" height=\"64\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM2-64x64.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33220\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM2-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM2-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM2-90x90.jpg 90w\" sizes=\"(max-width: 64px) 100vw, 64px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33220'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram3\/'><img width=\"64\" height=\"64\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM3-64x64.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33221\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM3-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM3-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM3-90x90.jpg 90w\" sizes=\"(max-width: 64px) 100vw, 64px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33221'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram4\/'><img width=\"64\" height=\"64\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM4-64x64.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33222\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM4-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM4-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM4-90x90.jpg 90w\" sizes=\"(max-width: 64px) 100vw, 64px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33222'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram5\/'><img width=\"64\" height=\"64\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM5-64x64.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33223\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM5-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM5-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM5-90x90.jpg 90w\" sizes=\"(max-width: 64px) 100vw, 64px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33223'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram6\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6-100x100.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33224\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6-100x100.jpg 100w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6-90x90.jpg 90w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33224'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/dhruva-natchathiram7\/'><img width=\"64\" height=\"64\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM7-64x64.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DHRUVA NATCHATHIRAM WORKING IMAGES\" decoding=\"async\" loading=\"lazy\" aria-describedby=\"gallery-1-33225\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM7-64x64.jpg 64w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM7-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM7-90x90.jpg 90w\" sizes=\"(max-width: 64px) 100vw, 64px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-33225'>\n\t\t\t\tDHRUVA NATCHATHIRAM WORKING IMAGES\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":33224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[101],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision<\/title>\n<meta name=\"description\" content=\"Chennaivision\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision\" \/>\n<meta property=\"og:description\" content=\"Chennaivision\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\" \/>\n<meta property=\"og:site_name\" content=\"Chennaivision\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chennaivision\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-03T07:37:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chennaivision\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chennaivision\" \/>\n<meta name=\"twitter:site\" content=\"@chennaivision\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chennaivision\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\"},\"author\":{\"name\":\"Chennaivision\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b\"},\"headline\":\"DHRUVA NATCHATHIRAM WORKING IMAGES\",\"datePublished\":\"2017-11-03T07:37:08+00:00\",\"dateModified\":\"2017-11-03T07:37:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\"},\"articleSection\":[\"Tamil Movie Photos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\",\"name\":\"DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision\",\"isPartOf\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#website\"},\"datePublished\":\"2017-11-03T07:37:08+00:00\",\"dateModified\":\"2017-11-03T07:37:08+00:00\",\"description\":\"Chennaivision\",\"breadcrumb\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chennaivision.com\/tamil-movies\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHRUVA NATCHATHIRAM WORKING IMAGES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#website\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/\",\"name\":\"Chennaivision\",\"description\":\"Get Today Latest Chennai, Movie, India News &amp; Gold Rate\",\"publisher\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chennaivision.com\/tamil-movies\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\",\"name\":\"V India\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1\",\"width\":263,\"height\":62,\"caption\":\"V India\"},\"image\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/chennaivision\",\"https:\/\/twitter.com\/chennaivision\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b\",\"name\":\"Chennaivision\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g\",\"caption\":\"Chennaivision\"},\"sameAs\":[\"http:\/\/vindia.net\/\"],\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/author\/cv_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision","description":"Chennaivision","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/","og_locale":"en_US","og_type":"article","og_title":"DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision","og_description":"Chennaivision","og_url":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/","og_site_name":"Chennaivision","article_publisher":"https:\/\/facebook.com\/chennaivision","article_published_time":"2017-11-03T07:37:08+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/11\/DHRUVA-NATCHATHIRAM6.jpg","type":"image\/jpeg"}],"author":"Chennaivision","twitter_card":"summary_large_image","twitter_creator":"@chennaivision","twitter_site":"@chennaivision","twitter_misc":{"Written by":"Chennaivision"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#article","isPartOf":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/"},"author":{"name":"Chennaivision","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b"},"headline":"DHRUVA NATCHATHIRAM WORKING IMAGES","datePublished":"2017-11-03T07:37:08+00:00","dateModified":"2017-11-03T07:37:08+00:00","mainEntityOfPage":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization"},"articleSection":["Tamil Movie Photos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/","url":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/","name":"DHRUVA NATCHATHIRAM WORKING IMAGES - Chennaivision","isPartOf":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#website"},"datePublished":"2017-11-03T07:37:08+00:00","dateModified":"2017-11-03T07:37:08+00:00","description":"Chennaivision","breadcrumb":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chennaivision.com\/tamil-movies\/dhruva-natchathiram-working-images\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chennaivision.com\/tamil-movies\/"},{"@type":"ListItem","position":2,"name":"DHRUVA NATCHATHIRAM WORKING IMAGES"}]},{"@type":"WebSite","@id":"https:\/\/chennaivision.com\/tamil-movies\/#website","url":"https:\/\/chennaivision.com\/tamil-movies\/","name":"Chennaivision","description":"Get Today Latest Chennai, Movie, India News &amp; Gold Rate","publisher":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chennaivision.com\/tamil-movies\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization","name":"V India","url":"https:\/\/chennaivision.com\/tamil-movies\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1","contentUrl":"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1","width":263,"height":62,"caption":"V India"},"image":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/chennaivision","https:\/\/twitter.com\/chennaivision"]},{"@type":"Person","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b","name":"Chennaivision","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g","caption":"Chennaivision"},"sameAs":["http:\/\/vindia.net\/"],"url":"https:\/\/chennaivision.com\/tamil-movies\/author\/cv_admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/33219"}],"collection":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/comments?post=33219"}],"version-history":[{"count":1,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/33219\/revisions"}],"predecessor-version":[{"id":33226,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/33219\/revisions\/33226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/media\/33224"}],"wp:attachment":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/media?parent=33219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/categories?post=33219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/tags?post=33219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}