{"id":30605,"date":"2017-07-25T10:23:46","date_gmt":"2017-07-25T10:23:46","guid":{"rendered":"https:\/\/chennaivision.com\/tamil-movies\/?p=30605"},"modified":"2017-09-02T05:50:48","modified_gmt":"2017-09-02T05:50:48","slug":"kargil-tamil-movie-photos","status":"publish","type":"post","link":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/","title":{"rendered":"Kargil Tamil Movie Photos"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-30605 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-1\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-1-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-1-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-1-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-1-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-2\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-2-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-2-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-2-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-2-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-3\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-3-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-3-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-3-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-3-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-4\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-4-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-4-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-4-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-4-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-5\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-5-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-5-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-5-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-5-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-6\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-6-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-6-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-6-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-6-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-7\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-7-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-7-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-7-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-7-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/kargil-tamil-movie-photos-8\/'><img width=\"100\" height=\"100\" src=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-100x100.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-100x100.jpg 100w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-150x150.jpg 150w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-200x200.jpg 200w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-90x90.jpg 90w, https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8-64x64.jpg 64w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":31479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[101],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kargil Tamil Movie Photos - Chennaivision<\/title>\n<meta name=\"description\" content=\"Chennaivision\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kargil Tamil Movie Photos - Chennaivision\" \/>\n<meta property=\"og:description\" content=\"Chennaivision\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\" \/>\n<meta property=\"og:site_name\" content=\"Chennaivision\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/chennaivision\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-25T10:23:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-02T05:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chennaivision\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@chennaivision\" \/>\n<meta name=\"twitter:site\" content=\"@chennaivision\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chennaivision\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\"},\"author\":{\"name\":\"Chennaivision\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b\"},\"headline\":\"Kargil Tamil Movie Photos\",\"datePublished\":\"2017-07-25T10:23:46+00:00\",\"dateModified\":\"2017-09-02T05:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\"},\"articleSection\":[\"Tamil Movie Photos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\",\"name\":\"Kargil Tamil Movie Photos - Chennaivision\",\"isPartOf\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#website\"},\"datePublished\":\"2017-07-25T10:23:46+00:00\",\"dateModified\":\"2017-09-02T05:50:48+00:00\",\"description\":\"Chennaivision\",\"breadcrumb\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/chennaivision.com\/tamil-movies\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kargil Tamil Movie Photos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#website\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/\",\"name\":\"Chennaivision\",\"description\":\"Get Today Latest Chennai, Movie, India News &amp; Gold Rate\",\"publisher\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chennaivision.com\/tamil-movies\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#organization\",\"name\":\"V India\",\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1\",\"width\":263,\"height\":62,\"caption\":\"V India\"},\"image\":{\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/chennaivision\",\"https:\/\/twitter.com\/chennaivision\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b\",\"name\":\"Chennaivision\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g\",\"caption\":\"Chennaivision\"},\"sameAs\":[\"http:\/\/vindia.net\/\"],\"url\":\"https:\/\/chennaivision.com\/tamil-movies\/author\/cv_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kargil Tamil Movie Photos - Chennaivision","description":"Chennaivision","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/","og_locale":"en_US","og_type":"article","og_title":"Kargil Tamil Movie Photos - Chennaivision","og_description":"Chennaivision","og_url":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/","og_site_name":"Chennaivision","article_publisher":"https:\/\/facebook.com\/chennaivision","article_published_time":"2017-07-25T10:23:46+00:00","article_modified_time":"2017-09-02T05:50:48+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2017\/07\/Kargil-Tamil-Movie-Photos-8.jpg","type":"image\/jpeg"}],"author":"Chennaivision","twitter_card":"summary_large_image","twitter_creator":"@chennaivision","twitter_site":"@chennaivision","twitter_misc":{"Written by":"Chennaivision"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#article","isPartOf":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/"},"author":{"name":"Chennaivision","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b"},"headline":"Kargil Tamil Movie Photos","datePublished":"2017-07-25T10:23:46+00:00","dateModified":"2017-09-02T05:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization"},"articleSection":["Tamil Movie Photos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/","url":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/","name":"Kargil Tamil Movie Photos - Chennaivision","isPartOf":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#website"},"datePublished":"2017-07-25T10:23:46+00:00","dateModified":"2017-09-02T05:50:48+00:00","description":"Chennaivision","breadcrumb":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chennaivision.com\/tamil-movies\/kargil-tamil-movie-photos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chennaivision.com\/tamil-movies\/"},{"@type":"ListItem","position":2,"name":"Kargil Tamil Movie Photos"}]},{"@type":"WebSite","@id":"https:\/\/chennaivision.com\/tamil-movies\/#website","url":"https:\/\/chennaivision.com\/tamil-movies\/","name":"Chennaivision","description":"Get Today Latest Chennai, Movie, India News &amp; Gold Rate","publisher":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chennaivision.com\/tamil-movies\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chennaivision.com\/tamil-movies\/#organization","name":"V India","url":"https:\/\/chennaivision.com\/tamil-movies\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1","contentUrl":"https:\/\/i2.wp.com\/chennaivision.com\/tamil-movies\/wp-content\/uploads\/2020\/02\/vindia-logo.png?fit=263%2C62&ssl=1","width":263,"height":62,"caption":"V India"},"image":{"@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/chennaivision","https:\/\/twitter.com\/chennaivision"]},{"@type":"Person","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/b29d439c689a7e54024f547df072dc8b","name":"Chennaivision","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chennaivision.com\/tamil-movies\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a87e39db3f3aeed8e2ddbf0d757baac?s=96&d=mm&r=g","caption":"Chennaivision"},"sameAs":["http:\/\/vindia.net\/"],"url":"https:\/\/chennaivision.com\/tamil-movies\/author\/cv_admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/30605"}],"collection":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/comments?post=30605"}],"version-history":[{"count":3,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/30605\/revisions"}],"predecessor-version":[{"id":31480,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/posts\/30605\/revisions\/31480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/media\/31479"}],"wp:attachment":[{"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/media?parent=30605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/categories?post=30605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chennaivision.com\/tamil-movies\/wp-json\/wp\/v2\/tags?post=30605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}